{"id":50525,"date":"2011-04-23T11:40:00","date_gmt":"2011-04-23T09:40:00","guid":{"rendered":"http:\/\/summer-lee.com.w013a091.kasserver.com\/index.php\/2011\/04\/23\/wish-post-no-4-little-helper-and-other-curiosities\/"},"modified":"2017-03-25T20:45:36","modified_gmt":"2017-03-25T19:45:36","slug":"wish-post-no-4-little-helper-and-other-curiosities","status":"publish","type":"post","link":"http:\/\/www.summer-lee.com\/index.php\/2011\/04\/23\/wish-post-no-4-little-helper-and-other-curiosities\/","title":{"rendered":"Wish Post No. 4 &#8211; Little helper and other curiosities"},"content":{"rendered":"<div style=\"text-align: center;\"><span style=\"color: #e06666; font-size: large;\"><b>Frohe Ostern\u00a0<\/b><\/span><\/div>\n<div style=\"text-align: center;\">\n<p><span style=\"color: #e06666; font-size: large;\"><b>Ich hoffe, der Osterhase bringt euch viele Leckerein \u2665<\/b><\/span><\/p>\n<p>Ich bringe euch nun den 4. Wunschpost. Heute geht es um kleine, n\u00fctzliche Helferlein und anderen Kuriosit\u00e4ten (Kitsch und Spa\u00df) aus Asien.<\/p>\n<p>Hier erst einmal die Links zu den Sachen, die ich bereits vorgestellt hatte:<\/p>\n<p><a href=\"http:\/\/summer-rain-and-cupcakes.blogspot.com\/2011\/03\/perfect-big-bun.html\"><span style=\"color: #e06666;\">1.) Big Bun Maker via Ebay aus HongKong<\/span><\/a><\/p>\n<\/div>\n<div style=\"text-align: center;\"><a href=\"http:\/\/summer-rain-and-cupcakes.blogspot.com\/2011\/04\/poppy-mint.html\"><span style=\"color: #e06666;\">2.) Beheizbare Wimpernzange aus HongKong f\u00fcr mehr Schwung<\/span><\/a><br \/>\n<a href=\"http:\/\/summer-rain-and-cupcakes.blogspot.com\/2011\/03\/alices-wonderland-is-my-home-look-at-my.html\"><span style=\"color: #e06666;\">3.) Passport Case f\u00fcr mehr Wonderland feeling \ud83d\ude42<\/span><\/a><\/div>\n<div style=\"text-align: center;\">Diese Dinge k\u00f6nnt ihr alle auf Ebay erwerben, die Links sind in den jeweiligen Posts, oder als Kommentar unter den Posts. Bei den Passport Cases gebt ihr das einfach in die Suchleiste bei Ebay und ihr habt die freie Wahl. Die drei Dinge kann ich mit gutem Gewissen weiterempfehlen.Nun zu den kleinen Helferlein, die ich noch nicht bestellt oder getestet habe, die aber meine Aufmerksamkeit erregt haben. Hierzu m\u00f6chte ich sagen, dass ich wirklich den Kitsch aus Asien liebe.<br \/>\nAber einen kleinen Schaden haben wir Asiaten auf alle F\u00e4lle, was Kitsch betrifft \u2665<br \/>\nBei Interesse m\u00fcsst ihr nur auf das rosane klicken, dann werdet ihr direkt weitergeleitet.<\/p>\n<p>1.) <a href=\"http:\/\/cgi.ebay.com\/ws\/eBayISAPI.dll?ViewItem&amp;item=170584856851&amp;var=470017087646&amp;ssPageName=STRK:MEWAX:IT#ht_2912wt_1141\"><span style=\"color: #e06666;\">Bunny Hairbands, \u00e4lterer Trend aus Asien: Cute Faktor &#8211; hoch!<\/span><\/a><\/p>\n<div style=\"clear: both; text-align: center;\"><img loading=\"lazy\" class=\"size-full wp-image-51031 aligncenter\" src=\"https:\/\/i2.wp.com\/summer-lee.com.w013a091.kasserver.com\/wp-content\/uploads\/2011\/04\/4801993212_9ce8f2703a.jpg?resize=500%2C500\" alt=\"4801993212_9ce8f2703a\" width=\"500\" height=\"500\" srcset=\"https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/4801993212_9ce8f2703a.jpg?w=500 500w, https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/4801993212_9ce8f2703a.jpg?resize=150%2C150 150w, https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/4801993212_9ce8f2703a.jpg?resize=300%2C300 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" data-recalc-dims=\"1\" \/><\/div>\n<p><span style=\"color: #741b47;\"><a href=\"http:\/\/www.google.de\/imgres?imgurl=http:\/\/lh3.ggpht.com\/_8EId9CFEnCE\/TNOJXPvvvcI\/AAAAAAAAG6E\/EEjOG5e9EgU\/4801993212_9ce8f2703a.jpg&amp;imgrefurl=http:\/\/adalessa.blogspot.com\/2010\/11\/usamimi-bunny-hair-band-style-guide.html&amp;usg=__O42zlpPuDmNkfAuSWwypqUYwp_E=&amp;h=500&amp;w=500&amp;sz=78&amp;hl=de&amp;start=7&amp;zoom=1&amp;um=1&amp;itbs=1&amp;tbnid=g2i86hkFxqnhLM:&amp;tbnh=130&amp;tbnw=130&amp;prev=\/search%3Fq%3Dbunny%2Bhairbands%2Bebay%26um%3D1%26hl%3Dde%26biw%3D1280%26bih%3D636%26tbm%3Disch&amp;ei=QJeyTfH2IJCG4Aaa3J2EDA\">via<\/a><\/span><\/p>\n<p>2.) <a href=\"http:\/\/cgi.ebay.com\/ws\/eBayISAPI.dll?ViewItem&amp;item=270725501576&amp;ssPageName=STRK:MEWAX:IT#ht_3823wt_910\"><span style=\"color: #e06666;\">Snap On Soda Bottle Tops &#8211; Genial. Ich hasse Dosen, da die so schnell abstehen etc.<\/span><\/a><\/p>\n<div style=\"clear: both; text-align: center;\"><img loading=\"lazy\" class=\"size-full wp-image-51032 aligncenter\" src=\"https:\/\/i0.wp.com\/summer-lee.com.w013a091.kasserver.com\/wp-content\/uploads\/2011\/04\/bottle-top.jpg?resize=297%2C297\" alt=\"bottle-top\" width=\"297\" height=\"297\" srcset=\"https:\/\/i1.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/bottle-top.jpg?w=297 297w, https:\/\/i1.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/bottle-top.jpg?resize=150%2C150 150w\" sizes=\"(max-width: 297px) 100vw, 297px\" data-recalc-dims=\"1\" \/><\/div>\n<p><span style=\"color: #741b47;\">via<\/span><\/p>\n<p>3.) <a href=\"http:\/\/cgi.ebay.com\/Japan-False-Eyelash-Applicator-Mascara-Eye-Lash-Fake-nw-\/260740204375?pt=LH_DefaultDomain_0&amp;var=&amp;hash=item826403ccb3\"><span style=\"color: #e06666;\">False Lashes Applicator &#8211; Hilft das wirklich?? Bin skeptisch&#8230;<\/span><\/a><\/p>\n<div style=\"clear: both; text-align: center;\"><\/div>\n<p>4.) <a href=\"http:\/\/cgi.ebay.com\/Japan-Mood-Makeup-Tool-Blusher-Cheek-Guide-Card-Helper-\/170614688212#ht_4754wt_910\"><span style=\"color: #e06666;\">Cheek Blush Guide &#8211; How To Look Shy, Cute, Sexy&#8230; Funny!<\/span><\/a><br \/>\nVerschieden Formen, die man sich an die Wangen h\u00e4lt um zu blushen. Demnach sollte man s\u00fc\u00df, sch\u00fcchtern oder auch sexy wirken. Ich finds lustig \ud83d\ude42<\/p>\n<div style=\"clear: both; text-align: center;\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-51033\" src=\"https:\/\/i1.wp.com\/summer-lee.com.w013a091.kasserver.com\/wp-content\/uploads\/2011\/04\/Wholesale-Free-Shipping-NEW-Makeup-Tool-Blush-Cheek-Guide-Card-Helper.jpg?resize=404%2C454\" alt=\"Wholesale-Free-Shipping-NEW-Makeup-Tool-Blush-Cheek-Guide-Card-Helper\" width=\"404\" height=\"454\" srcset=\"https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/Wholesale-Free-Shipping-NEW-Makeup-Tool-Blush-Cheek-Guide-Card-Helper.jpg?w=404 404w, https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/Wholesale-Free-Shipping-NEW-Makeup-Tool-Blush-Cheek-Guide-Card-Helper.jpg?resize=267%2C300 267w\" sizes=\"(max-width: 404px) 100vw, 404px\" data-recalc-dims=\"1\" \/><\/div>\n<div style=\"clear: both; text-align: center;\"><\/div>\n<div style=\"clear: both; text-align: center;\">5.) <a href=\"http:\/\/cgi.ebay.com\/3in1-Mascara-Applicator-Guide-Tool-Eyelash-Comb-Makeup-\/120709183379?pt=UK_HealthBeauty_Other_RL&amp;hash=item1c1ad3f793#ht_3322wt_1141\"><span style=\"color: #e06666;\">Mascara Applicator Guide &#8211; H\u00f6rt sich gut an. Vielleicht teste ich das mal&#8230;<\/span><\/a><\/div>\n<div style=\"clear: both; text-align: center;\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-51035\" src=\"https:\/\/i2.wp.com\/summer-lee.com.w013a091.kasserver.com\/wp-content\/uploads\/2011\/04\/SKU011501.0.jpg?resize=666%2C325\" alt=\"SKU011501.0\" width=\"666\" height=\"325\" srcset=\"https:\/\/i1.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/SKU011501.0.jpg?w=666 666w, https:\/\/i1.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/SKU011501.0.jpg?resize=300%2C146 300w\" sizes=\"(max-width: 666px) 100vw, 666px\" data-recalc-dims=\"1\" \/><\/div>\n<p>Also, es reicht erst mal f\u00fcr Heute \ud83d\ude42<br \/>\nHoffe ihr findet die Sachen genauso lustig, spannend und teilweise komisch wie ich xD<\/p>\n<p>AB IN DIE SONNE!!<\/p>\n<p>Love, Summer<\/p>\n<p>PS: Liebe Gr\u00fc\u00dfe an Anonym \ud83d\ude42<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Frohe Ostern\u00a0 Ich hoffe, der Osterhase bringt euch viele Leckerein \u2665 Ich bringe euch nun den 4. Wunschpost. Heute geht es um kleine, n\u00fctzliche Helferlein und anderen Kuriosit\u00e4ten (Kitsch und Spa\u00df) aus Asien. Hier erst einmal die Links zu den Sachen, die ich bereits vorgestellt hatte: 1.) Big Bun Maker via Ebay aus HongKong 2.) &#8230;<\/p>\n","protected":false},"author":1,"featured_media":51033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"spay_email":""},"categories":[111],"tags":[360],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/www.summer-lee.com\/wp-content\/uploads\/2011\/04\/Wholesale-Free-Shipping-NEW-Makeup-Tool-Blush-Cheek-Guide-Card-Helper.jpg?fit=404%2C454","_links":{"self":[{"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/posts\/50525"}],"collection":[{"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/comments?post=50525"}],"version-history":[{"count":4,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/posts\/50525\/revisions"}],"predecessor-version":[{"id":56150,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/posts\/50525\/revisions\/56150"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/media\/51033"}],"wp:attachment":[{"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/media?parent=50525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/categories?post=50525"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.summer-lee.com\/index.php\/wp-json\/wp\/v2\/tags?post=50525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}